{"id":12258,"date":"2021-09-28T07:58:39","date_gmt":"2021-09-28T12:58:39","guid":{"rendered":"https:\/\/gadgualaquiza.gob.ec\/web\/?p=12258"},"modified":"2021-09-28T07:58:44","modified_gmt":"2021-09-28T12:58:44","slug":"feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/","title":{"rendered":"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD"},"content":{"rendered":"\n<p>La ma\u00f1ana y tarde del s\u00e1bado 26 de septiembre, se apoyo la iniciativa, emprendimiento y ganas de superaci\u00f3n de las personas con discapacidad, quienes son expertas en mejorar continuamente y en adaptarse a los cambios, transforman sus habilidades en obras de arte y, muchos de ellos, hacen que su habilidad se convierta en un sustento para sus familias.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana y tarde del s\u00e1bado 26 de septiembre, se<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":12259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.7 (Yoast SEO v22.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD | Gad Municipal de Gualaquiza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD\" \/>\n<meta property=\"og:description\" content=\"La ma\u00f1ana y tarde del s\u00e1bado 26 de septiembre, se [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Gad Municipal de Gualaquiza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GADMGualaquiza\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-28T12:58:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-28T12:58:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Pesantez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gadgualaquiza\" \/>\n<meta name=\"twitter:site\" content=\"@gadgualaquiza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Pesantez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\"},\"author\":{\"name\":\"Fernando Pesantez\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f\"},\"headline\":\"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD\",\"datePublished\":\"2021-09-28T12:58:39+00:00\",\"dateModified\":\"2021-09-28T12:58:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\"},\"wordCount\":70,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg\",\"articleSection\":[\"ALCALDE\",\"NOTICIAS RECIENTES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\",\"name\":\"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD | Gad Municipal de Gualaquiza\",\"isPartOf\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg\",\"datePublished\":\"2021-09-28T12:58:39+00:00\",\"dateModified\":\"2021-09-28T12:58:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg\",\"contentUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gadgualaquiza.gob.ec\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#website\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/\",\"name\":\"Gad Municipal de Gualaquiza\",\"description\":\"Gualaquiza tiene futuro\",\"publisher\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gadgualaquiza.gob.ec\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#organization\",\"name\":\"GAD Municipal de Gualaquiza\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png\",\"contentUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png\",\"width\":378,\"height\":168,\"caption\":\"GAD Municipal de Gualaquiza\"},\"image\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GADMGualaquiza\/\",\"https:\/\/twitter.com\/gadgualaquiza\",\"https:\/\/www.youtube.com\/channel\/UCevG9dVTc47am3Z-S4sgeRg\/videos?disable_polymer=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f\",\"name\":\"Fernando Pesantez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g\",\"caption\":\"Fernando Pesantez\"},\"sameAs\":[\"http:\/\/www.gadgualaquiza.gob.ec\"],\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/author\/fpesantez\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD | Gad Municipal de Gualaquiza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/","og_locale":"es_ES","og_type":"article","og_title":"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD","og_description":"La ma\u00f1ana y tarde del s\u00e1bado 26 de septiembre, se [\u2026]","og_url":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/","og_site_name":"Gad Municipal de Gualaquiza","article_publisher":"https:\/\/www.facebook.com\/GADMGualaquiza\/","article_published_time":"2021-09-28T12:58:39+00:00","article_modified_time":"2021-09-28T12:58:44+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg","type":"image\/jpeg"}],"author":"Fernando Pesantez","twitter_card":"summary_large_image","twitter_creator":"@gadgualaquiza","twitter_site":"@gadgualaquiza","twitter_misc":{"Escrito por":"Fernando Pesantez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#article","isPartOf":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/"},"author":{"name":"Fernando Pesantez","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f"},"headline":"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD","datePublished":"2021-09-28T12:58:39+00:00","dateModified":"2021-09-28T12:58:44+00:00","mainEntityOfPage":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/"},"wordCount":70,"commentCount":0,"publisher":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#organization"},"image":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg","articleSection":["ALCALDE","NOTICIAS RECIENTES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/","url":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/","name":"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD | Gad Municipal de Gualaquiza","isPartOf":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage"},"image":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg","datePublished":"2021-09-28T12:58:39+00:00","dateModified":"2021-09-28T12:58:44+00:00","breadcrumb":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#primaryimage","url":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg","contentUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/09\/FERIA.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/09\/28\/feria-de-habilidades-y-emprendimientos-de-las-personas-con-discapacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gadgualaquiza.gob.ec\/web\/"},{"@type":"ListItem","position":2,"name":"FERIA DE HABILIDADES Y EMPRENDIMIENTOS DE LAS PERSONAS CON DISCAPACIDAD"}]},{"@type":"WebSite","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#website","url":"https:\/\/gadgualaquiza.gob.ec\/web\/","name":"Gad Municipal de Gualaquiza","description":"Gualaquiza tiene futuro","publisher":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gadgualaquiza.gob.ec\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#organization","name":"GAD Municipal de Gualaquiza","url":"https:\/\/gadgualaquiza.gob.ec\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/","url":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png","contentUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png","width":378,"height":168,"caption":"GAD Municipal de Gualaquiza"},"image":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GADMGualaquiza\/","https:\/\/twitter.com\/gadgualaquiza","https:\/\/www.youtube.com\/channel\/UCevG9dVTc47am3Z-S4sgeRg\/videos?disable_polymer=1"]},{"@type":"Person","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f","name":"Fernando Pesantez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g","caption":"Fernando Pesantez"},"sameAs":["http:\/\/www.gadgualaquiza.gob.ec"],"url":"https:\/\/gadgualaquiza.gob.ec\/web\/author\/fpesantez\/"}]}},"_links":{"self":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts\/12258"}],"collection":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/comments?post=12258"}],"version-history":[{"count":1,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts\/12258\/revisions"}],"predecessor-version":[{"id":12260,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts\/12258\/revisions\/12260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/media\/12259"}],"wp:attachment":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/media?parent=12258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/categories?post=12258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/tags?post=12258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}