{"id":12056,"date":"2021-08-06T15:51:10","date_gmt":"2021-08-06T20:51:10","guid":{"rendered":"https:\/\/gadgualaquiza.gob.ec\/web\/?p=12056"},"modified":"2021-08-06T15:51:16","modified_gmt":"2021-08-06T20:51:16","slug":"visita-coordinador-de-salud-zona-6","status":"publish","type":"post","link":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/","title":{"rendered":"VISITA COORDINADOR DE SALUD ZONA 6"},"content":{"rendered":"\n<p>El Ing. Francis Pav\u00f3n, alcalde de Gualaquiza, recibi\u00f3 en su despacho la visita del Dr. Fausto Idrovo, coordinador de Salud de la Zona 6, y sus t\u00e9cnicos, con quienes realizaron un an\u00e1lisis respecto a la infraestructura sanitaria que posee nuestro cant\u00f3n.<\/p>\n\n\n\n<p>En este sentido, el burgomaestre expuso su compromiso con el Ministerio de Salud P\u00fablica para determinar y legalizar un lote de terreno, en donde se pueda emplazar un proyecto para la construcci\u00f3n de un nuevo hospital y as\u00ed buscar los recursos necesarios que permitan cristalizar esta importante obra.<\/p>\n\n\n\n<p>En esta visita, se realiz\u00f3, tambi\u00e9n, un recorrido al lugar en donde se pretende realizar la construcci\u00f3n.La inversi\u00f3n en salud es una prioridad para nuestra administraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ing. Francis Pav\u00f3n, alcalde de Gualaquiza, recibi\u00f3 en su<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":12057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.7 (Yoast SEO v22.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VISITA COORDINADOR DE SALUD ZONA 6 | Gad Municipal de Gualaquiza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VISITA COORDINADOR DE SALUD ZONA 6\" \/>\n<meta property=\"og:description\" content=\"El Ing. Francis Pav\u00f3n, alcalde de Gualaquiza, recibi\u00f3 en su [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Gad Municipal de Gualaquiza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GADMGualaquiza\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-06T20:51:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-06T20:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Pesantez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gadgualaquiza\" \/>\n<meta name=\"twitter:site\" content=\"@gadgualaquiza\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Pesantez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\"},\"author\":{\"name\":\"Fernando Pesantez\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f\"},\"headline\":\"VISITA COORDINADOR DE SALUD ZONA 6\",\"datePublished\":\"2021-08-06T20:51:10+00:00\",\"dateModified\":\"2021-08-06T20:51:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\"},\"wordCount\":130,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#organization\"},\"image\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg\",\"articleSection\":[\"NOTICIAS RECIENTES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\",\"name\":\"VISITA COORDINADOR DE SALUD ZONA 6 | Gad Municipal de Gualaquiza\",\"isPartOf\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg\",\"datePublished\":\"2021-08-06T20:51:10+00:00\",\"dateModified\":\"2021-08-06T20:51:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg\",\"contentUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gadgualaquiza.gob.ec\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VISITA COORDINADOR DE SALUD ZONA 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#website\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/\",\"name\":\"Gad Municipal de Gualaquiza\",\"description\":\"Gualaquiza tiene futuro\",\"publisher\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gadgualaquiza.gob.ec\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#organization\",\"name\":\"GAD Municipal de Gualaquiza\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png\",\"contentUrl\":\"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png\",\"width\":378,\"height\":168,\"caption\":\"GAD Municipal de Gualaquiza\"},\"image\":{\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GADMGualaquiza\/\",\"https:\/\/twitter.com\/gadgualaquiza\",\"https:\/\/www.youtube.com\/channel\/UCevG9dVTc47am3Z-S4sgeRg\/videos?disable_polymer=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f\",\"name\":\"Fernando Pesantez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g\",\"caption\":\"Fernando Pesantez\"},\"sameAs\":[\"http:\/\/www.gadgualaquiza.gob.ec\"],\"url\":\"https:\/\/gadgualaquiza.gob.ec\/web\/author\/fpesantez\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VISITA COORDINADOR DE SALUD ZONA 6 | Gad Municipal de Gualaquiza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/","og_locale":"es_ES","og_type":"article","og_title":"VISITA COORDINADOR DE SALUD ZONA 6","og_description":"El Ing. Francis Pav\u00f3n, alcalde de Gualaquiza, recibi\u00f3 en su [\u2026]","og_url":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/","og_site_name":"Gad Municipal de Gualaquiza","article_publisher":"https:\/\/www.facebook.com\/GADMGualaquiza\/","article_published_time":"2021-08-06T20:51:10+00:00","article_modified_time":"2021-08-06T20:51:16+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg","type":"image\/jpeg"}],"author":"Fernando Pesantez","twitter_card":"summary_large_image","twitter_creator":"@gadgualaquiza","twitter_site":"@gadgualaquiza","twitter_misc":{"Escrito por":"Fernando Pesantez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#article","isPartOf":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/"},"author":{"name":"Fernando Pesantez","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f"},"headline":"VISITA COORDINADOR DE SALUD ZONA 6","datePublished":"2021-08-06T20:51:10+00:00","dateModified":"2021-08-06T20:51:16+00:00","mainEntityOfPage":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/"},"wordCount":130,"commentCount":0,"publisher":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#organization"},"image":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage"},"thumbnailUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg","articleSection":["NOTICIAS RECIENTES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/","url":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/","name":"VISITA COORDINADOR DE SALUD ZONA 6 | Gad Municipal de Gualaquiza","isPartOf":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage"},"image":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage"},"thumbnailUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg","datePublished":"2021-08-06T20:51:10+00:00","dateModified":"2021-08-06T20:51:16+00:00","breadcrumb":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#primaryimage","url":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg","contentUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2021\/08\/SALUD.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/2021\/08\/06\/visita-coordinador-de-salud-zona-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gadgualaquiza.gob.ec\/web\/"},{"@type":"ListItem","position":2,"name":"VISITA COORDINADOR DE SALUD ZONA 6"}]},{"@type":"WebSite","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#website","url":"https:\/\/gadgualaquiza.gob.ec\/web\/","name":"Gad Municipal de Gualaquiza","description":"Gualaquiza tiene futuro","publisher":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gadgualaquiza.gob.ec\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#organization","name":"GAD Municipal de Gualaquiza","url":"https:\/\/gadgualaquiza.gob.ec\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/","url":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png","contentUrl":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-content\/uploads\/2018\/03\/logo.png","width":378,"height":168,"caption":"GAD Municipal de Gualaquiza"},"image":{"@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GADMGualaquiza\/","https:\/\/twitter.com\/gadgualaquiza","https:\/\/www.youtube.com\/channel\/UCevG9dVTc47am3Z-S4sgeRg\/videos?disable_polymer=1"]},{"@type":"Person","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/aa08bcd7909c6672766f9edcdd9e722f","name":"Fernando Pesantez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gadgualaquiza.gob.ec\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efb8a6cdb2ab57ff97c950283b2ffe44?s=96&d=mm&r=g","caption":"Fernando Pesantez"},"sameAs":["http:\/\/www.gadgualaquiza.gob.ec"],"url":"https:\/\/gadgualaquiza.gob.ec\/web\/author\/fpesantez\/"}]}},"_links":{"self":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts\/12056"}],"collection":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/comments?post=12056"}],"version-history":[{"count":1,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts\/12056\/revisions"}],"predecessor-version":[{"id":12058,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/posts\/12056\/revisions\/12058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/media\/12057"}],"wp:attachment":[{"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/media?parent=12056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/categories?post=12056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gadgualaquiza.gob.ec\/web\/wp-json\/wp\/v2\/tags?post=12056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}